{"id":22,"date":"2008-07-01T15:06:39","date_gmt":"2008-07-01T13:06:39","guid":{"rendered":"http:\/\/portasanitas.de\/aktuell\/?p=22"},"modified":"2011-06-15T11:30:44","modified_gmt":"2011-06-15T09:30:44","slug":"seminar-ozontherapie-an-der-freien-heilpraktikerschule-freiburg","status":"publish","type":"post","link":"https:\/\/www.portasanitas.de\/aktuell\/2008\/07\/seminar-ozontherapie-an-der-freien-heilpraktikerschule-freiburg\/","title":{"rendered":"Seminar Ozontherapie an der Freien Heilpraktikerschule Freiburg"},"content":{"rendered":"<p>Fr\u00fcher als &#8222;Blutw\u00e4sche&#8220; bezeichnet, beschreibt die Ozontherapie das intraven\u00f6se Anreichern des Patienten eigenen Blutes mit einer Ozon-Sauerstoff-Mischung. Voraussetzung f\u00fcr den Kursbesuch: Injektionskurs.<br \/>\n<strong>Dozent:<\/strong> Bernhard Kromer (HP)<br \/>\n<strong>Termine:<\/strong> Di. 08.\/ Do. 10.\/ Di. 15.\/ Mo. 21. Juli jeweils 13 bis 16 Uhr<br \/>\n<strong>Geb\u00fchr:<\/strong> Euro 80,- bzw. Euro 72,- erm\u00e4\u00dfigt <\/p>\n<p>Weitere Informationen finden Sie unter<br \/>\n<a href=\"http:\/\/freie-heilpraktikerschule.de\">www.freie-heilpraktikerschule.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fr\u00fcher als &#8222;Blutw\u00e4sche&#8220; bezeichnet, beschreibt die Ozontherapie das intraven\u00f6se Anreichern des Patienten eigenen Blutes mit einer Ozon-Sauerstoff-Mischung. Voraussetzung f\u00fcr den Kursbesuch: Injektionskurs. Dozent: Bernhard Kromer (HP) Termine: Di. 08.\/ Do. 10.\/ Di. 15.\/ Mo. 21. Juli jeweils 13 bis 16 Uhr Geb\u00fchr: Euro 80,- bzw. Euro 72,- erm\u00e4\u00dfigt Weitere Informationen finden Sie unter www.freie-heilpraktikerschule.de<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[540],"tags":[27,26,25],"class_list":["post-22","post","type-post","status-publish","format-standard","hentry","category-heilpraktiker-archiv","tag-blutwasche","tag-freiburg","tag-ozontherapie"],"_links":{"self":[{"href":"https:\/\/www.portasanitas.de\/aktuell\/wp-json\/wp\/v2\/posts\/22","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.portasanitas.de\/aktuell\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.portasanitas.de\/aktuell\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.portasanitas.de\/aktuell\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.portasanitas.de\/aktuell\/wp-json\/wp\/v2\/comments?post=22"}],"version-history":[{"count":2,"href":"https:\/\/www.portasanitas.de\/aktuell\/wp-json\/wp\/v2\/posts\/22\/revisions"}],"predecessor-version":[{"id":699,"href":"https:\/\/www.portasanitas.de\/aktuell\/wp-json\/wp\/v2\/posts\/22\/revisions\/699"}],"wp:attachment":[{"href":"https:\/\/www.portasanitas.de\/aktuell\/wp-json\/wp\/v2\/media?parent=22"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.portasanitas.de\/aktuell\/wp-json\/wp\/v2\/categories?post=22"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.portasanitas.de\/aktuell\/wp-json\/wp\/v2\/tags?post=22"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}